{"id":1830,"date":"2021-06-03T10:25:43","date_gmt":"2021-06-03T08:25:43","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=1830"},"modified":"2021-06-22T12:11:38","modified_gmt":"2021-06-22T10:11:38","slug":"chopp","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/en\/chopp\/","title":{"rendered":"Chopp"},"content":{"rendered":"<p><span style=\"font-size: small;\">Foto di &#8220;<\/span><a style=\"font-size: small;\" href=\"http:\/\/saiasparacopos.blogspot.com\/2011\/05\/fabricacao-da-cervejachopp.html\" target=\"_blank\" rel=\"noopener\">Evidence &#8211; saias para copos<\/a><span style=\"font-size: small;\">&#8220;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Chopp<\/em><\/strong> o <strong><em>Chope<\/em><\/strong>\u00a0non \u00e8 birra alla spina!<br \/>\n<em><strong>Chopp<\/strong><\/em>\u00a0\u00e8 la birra non pastorizzata che non va imbottigliata ma messa in barile, e che si conserva soltanto per 10 &#8211; 15 giorni. La parola deriva da schopp, che in tedesco \u00e8 una misura equivalente a 300 ml.<br \/>\nL&#8217;espressione &#8220;vamos tomar um <em>chopp<\/em>?&#8221; (andiamo a prende una birra?), &#8220;vamos marcar um <em>chopp<\/em>?&#8221; (quando ci vediamo?) e &#8220;vamos tomar uma Brahma?&#8221; (una delle pi\u00f9 importante marche di birra e <em>chopp<\/em>) sono diventate sinonimo di ritrovarsi per chiacchierare.<\/p>\n<p>Uno dei video per vedere come si serve il <strong><em>chopp<\/em><\/strong>: <a href=\"http:\/\/www.youtube.com\/watch?v=NF5B83pr-Zo\" target=\"_blank\" rel=\"noopener\">O Chope Padr\u00e3o Original<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto di &#8220;Evidence &#8211; saias para copos&#8220; &nbsp; Chopp o Chope\u00a0non \u00e8 birra alla spina! Chopp\u00a0\u00e8 la birra non pastorizzata che non va imbottigliata ma messa in barile, e che si conserva soltanto per 10 &#8211; 15 giorni. La parola deriva da schopp, che in&hellip;<\/p>\n","protected":false},"author":2,"featured_media":610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilidade"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/comments?post=1830"}],"version-history":[{"count":3,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1830\/revisions"}],"predecessor-version":[{"id":5874,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1830\/revisions\/5874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media?parent=1830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/categories?post=1830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/tags?post=1830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}