{"id":1846,"date":"2021-06-05T12:04:22","date_gmt":"2021-06-05T10:04:22","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=1846"},"modified":"2021-06-05T12:04:22","modified_gmt":"2021-06-05T10:04:22","slug":"tiquira-manioc-brandy","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/en\/tiquira-manioc-brandy\/","title":{"rendered":"Tiquira\u00a0(Manioc brandy)"},"content":{"rendered":"<div class=\"texttop\">\n<div class=\"fb-like fb_iframe_widget\" data-send=\"false\" data-layout=\"button_count\" data-width=\"50\" data-show-faces=\"false\" data-font=\"arial\">L&#8217;utilizzo della foto \u00e8 stato gentilmente concesso da Mariana Gutheil.<\/div>\n<p><a>\u00a0<\/a><\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div class=\"texttop\">\n<div>La <em><strong>tiquira<\/strong><\/em>\u00a0\u00e8 una acquavite di\u00a0manioca\u00a0con gradazione altissima che varia da 36\u00b0 a 54\u00b0, nata e prodotta artigianalmente nel\u00a0<i>Maranh\u00e3o<\/i>, stato del nordest del Brasile. Per distinguerla dalle altre acquaviti alla preparazione sono state aggiunte foglie di clementina che conferiscono questo inusitato color violaceo.<br \/>\nDovuto all&#8217;altissimo tenore alcoolico la <em><strong>tiquira<\/strong><\/em>\u00a0non \u00e8 per tutti, ma &#8220;s\u00f3 pra homi e mul\u00e9 macho&#8221; (soltanto per uomini e donne\u00a0<em>macho<\/em>).<br \/>\nAncora prima dell&#8217;arrivo dei colonizzatori gli\u00a0<em>\u00edndios<\/em> preparavano una bevanda fermentata con la manioca, il <em>cauim<\/em>, ma la tecnica della distillazione \u00e8 stata introdotta dagli europei. La <em><strong>tiquira<\/strong><\/em>\u00a0\u00e8 perci\u00f2 un prodotto locale frutto dell&#8217;incrocio della cultura indigena con i popoli immigranti.<\/div>\n<p><a>\u00a0<\/a><\/p>\n<\/div>\n<div class=\"bigImage\"><\/div>\n<div><\/div>\n<div class=\"middle\">\n<div class=\"ricetteIngredienti\">Fonte: Papo de bar, a web \u00e9 de quem bebe&#8230;<\/div>\n<\/div>\n<div class=\"updateRow\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;utilizzo della foto \u00e8 stato gentilmente concesso da Mariana Gutheil. \u00a0 La tiquira\u00a0\u00e8 una acquavite di\u00a0manioca\u00a0con gradazione altissima che varia da 36\u00b0 a 54\u00b0, nata e prodotta artigianalmente nel\u00a0Maranh\u00e3o, stato del nordest del Brasile. Per distinguerla dalle altre acquaviti alla preparazione sono state aggiunte foglie&hellip;<\/p>\n","protected":false},"author":2,"featured_media":669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-1846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingredienti-en"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":1,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1846\/revisions"}],"predecessor-version":[{"id":1862,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1846\/revisions\/1862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media\/669"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media?parent=1846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/categories?post=1846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/tags?post=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}