{"id":1880,"date":"2021-06-05T12:12:25","date_gmt":"2021-06-05T10:12:25","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=1880"},"modified":"2021-06-21T16:44:09","modified_gmt":"2021-06-21T14:44:09","slug":"pimenta-malagueta-chili-pepper","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/en\/pimenta-malagueta-chili-pepper\/","title":{"rendered":"Pimenta malagueta\u00a0(Chili pepper)"},"content":{"rendered":"<div class=\"texttop\">\n<div class=\"fb-like fb_iframe_widget\" data-send=\"false\" data-layout=\"button_count\" data-width=\"50\" data-show-faces=\"false\" data-font=\"arial\"><span style=\"font-size: small;\">Foto dal sito della &#8220;Secretaria de Agricultura e Abastecimento Agriculturasp (Governo do Estado de S\u00e3o Paulo)&#8221;.<\/span><\/div>\n<div data-send=\"false\" data-layout=\"button_count\" data-width=\"50\" data-show-faces=\"false\" data-font=\"arial\"><\/div>\n<p>&nbsp;<\/p>\n<div>Il peperoncino \u00e8 una pianta erbacea annuale originaria dell\u2019America Centrale e del Sul, da dove si \u00e8 diffusa durante il periodo delle grandi navigazioni (1492-1600) e, ora, \u00e8 coltivata e consumata da quasi tutti i popoli del mondo. Il peperoncino \u00e8 una delle principali spezie e il suo segno distintivo \u00e8 il sapore piccante bruciante. Ha un alto valore nutritivo, \u00e8 ricco di vitamine e di propriet\u00e0 analgesiche, energetiche, antiossidanti, anti-infiammatorie e anti-cancro, \u00e8 un vasodilatatore, produce una sensazione di benessere e riduce l&#8217;appetito.<br \/>\nIn Brasile il peperoncino \u00e8 coltivato in tutte le regioni ed \u00e8 consumato fresco al naturale o trasformato in vari modi. Le numerose specie e variet\u00e0 si differenziano per colore, forma, dimensione e &#8220;piccantezza&#8221;, che valorizzano e conferiscono caratteristiche peculiari agli alimenti.<br \/>\nLa piantina di peperoncino pu\u00f2 essere coltivata in giardino o in vaso dentro casa, in una posizione esposta al sole diretto, e ha un grande potenziale ornamentale.<br \/>\nI peperoni e i peperoncini appartengono alla famiglia delle\u00a0<i>Solanacee<\/i>\u00a0e al genere\u00a0<i>Capsicum<\/i>. Le quattro specie coltivate (domesticate) pi\u00f9 diffuse sono:<br \/>\n\u2022<i>\u00a0Capsicum annuum var. annuum<\/i>: le pi\u00f9 conosciute nel mondo, tra cui i peperoni (dolci), il peperoncino americano (dolce) e il peperoncino &#8220;Jalape\u00f1o&#8221; (piccantezza media).<br \/>\n\u2022\u00a0<i>Capsicum frutescens<\/i>: \u00e8 la &#8220;pimenta malagueta&#8221; (piccantezza media ad alta), conosciuta nel mondo come &#8220;tabasco&#8221; (frutto di 2,5 cm di lunghezza e larghezza media di 0,4 centimetri, colore rosso intenso a maturazione).<br \/>\n\u2022<i>\u00a0Capsicum chinense<\/i>: la pi\u00f9 brasiliana di tutte le specie coltivate, tra cui la &#8220;Pimenta-de-cheiro&#8221; (da dolce a piccantezza alta), il peperoncino &#8220;Biquinho&#8221; (piccantezza media), il peperoncino &#8220;Bode&#8221; (piccantezza alta), il peperoncino &#8220;Cumari-do-Par\u00e1&#8221; (piccantezza alta) e il peperoncino &#8220;Murupi&#8221; (piccantezza media ad alta).<br \/>\n\u2022\u00a0<i>Capsicum bacccatum var. pendulum<\/i>: diffusa nel Sud e Sud-Est del Brasile, tra cui il peperoncino &#8220;Dedo-de-Mo\u00e7a&#8221; conosciuto anche come &#8220;Chifre-de-viado&#8221; (piccantezza bassa) e il peperoncino &#8220;Cambuci&#8221; (dolce).<br \/>\n<a><br \/>\n<span style=\"font-size: small;\">Fonte: Embrapa (Empresa Brasileira de Pesquisa Agropecu\u00e1ria) <\/span><\/a><\/div>\n<div><a>\u00a0<\/a><\/div>\n<\/div>\n<div class=\"middle\">\n<div class=\"ricetteIngredienti\">\n<h4>Recipes<\/h4>\n<p><a href=\"https:\/\/saborbrasil.it\/en\/arroz-de-carreteiro-riso-del-mulattiere\/\" target=\"_blank\" rel=\"noopener\">Arroz de carreteiro (Mule driver&#8217;s rice)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/baiao-de-dois-riso-e-fagioli-cotti-insieme\/\" target=\"_blank\" rel=\"noopener\">Bai\u00e3o de dois\u00a0(Rice and black-eyed peas cooked together)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/bobo-de-camarao-gamberi-in-salsa-di-manioca\/\" target=\"_blank\" rel=\"noopener\">Bob\u00f3 de camar\u00e3o\u00a0(Prawn in Creamy Cassava Sauce)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/camarao-na-moranga-zucca-ripiena-di-gamberi\/\" target=\"_blank\" rel=\"noopener\">Camar\u00e3o na moranga\u00a0(Prawns in Pumpkin)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/cozido-boiled-meats-and-vegetables\/\" target=\"_blank\" rel=\"noopener\">Cozido\u00a0(Boiled Meats and Vegetables)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/feijoada-cooked-black-beans-with-pork\/\" target=\"_blank\" rel=\"noopener\">Feijoada (Brazilian Black Bean Stew)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/feijao-tropeiro-muleteer-beans\/\" target=\"_blank\" rel=\"noopener\">Feij\u00e3o-tropeiro\u00a0(Muleteer Beans)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/pacoca-de-carne-seca-shredded-salted-sun-dried-meat-with-manioc-flour\/\" target=\"_blank\" rel=\"noopener\">Pa\u00e7oca de carne seca\u00a0(Shredded salted sun dried meat with manioc flour )<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/quiabo-refogado-sauteed-okra\/\" target=\"_blank\" rel=\"noopener\">Quiabo refogado\u00a0(Saut\u00e9ed Okra)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/rabada-ao-vinho-tinto-coda-di-bue-in-umido-2\/\" target=\"_blank\" rel=\"noopener\">Rabada ao vinho tinto\u00a0(Oxtail Stew in Red Wine)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/saltenha-tortelloni-di-pollo\/\" target=\"_blank\" rel=\"noopener\">Saltenha\u00a0(Savoury pastry filled with chicken)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/sopa-de-grao-de-bico-com-macarraozinho-zuppa-di-ceci-con-ditalini\/\" target=\"_blank\" rel=\"noopener\">Sopa de gr\u00e3o-de-bico com macarr\u00e3ozinho\u00a0(Chickpea and pasta soup)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/tutu-de-feijao-crema-di-fagioli\/\" target=\"_blank\" rel=\"noopener\">Tutu de feij\u00e3o\u00a0(Black Bean Pur\u00e9e)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/vaca-atolada-beef-ribs-with-manioc\/\" target=\"_blank\" rel=\"noopener\">Vaca atolada\u00a0(Beef Ribs with Manioc)<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/en\/virado-a-paulista-bean-puree-with-pork\/\" target=\"_blank\" rel=\"noopener\">Virado \u00e0 paulista\u00a0(Bean Pur\u00e9e with<\/a> Pork)<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto dal sito della &#8220;Secretaria de Agricultura e Abastecimento Agriculturasp (Governo do Estado de S\u00e3o Paulo)&#8221;. &nbsp; Il peperoncino \u00e8 una pianta erbacea annuale originaria dell\u2019America Centrale e del Sul, da dove si \u00e8 diffusa durante il periodo delle grandi navigazioni (1492-1600) e, ora, \u00e8&hellip;<\/p>\n","protected":false},"author":2,"featured_media":738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-1880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingredienti-en"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":4,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions"}],"predecessor-version":[{"id":5682,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions\/5682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media?parent=1880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/categories?post=1880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/tags?post=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}