{"id":2025,"date":"2021-06-06T08:40:44","date_gmt":"2021-06-06T06:40:44","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=2025"},"modified":"2021-06-21T16:37:23","modified_gmt":"2021-06-21T14:37:23","slug":"caju-cashew-nut","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/en\/caju-cashew-nut\/","title":{"rendered":"Caj\u00fa\u00a0(cashew nut)"},"content":{"rendered":"<div class=\"texttop\">\n<div class=\"fb-like fb_iframe_widget\" data-send=\"false\" data-layout=\"button_count\" data-width=\"50\" data-show-faces=\"false\" data-font=\"arial\">Foto di Sydney Haddad.<br \/>\n<a><br \/>\n<\/a><\/p>\n<div>Il &#8220;cajueiro&#8221; (<em>Anacardium occidentale L.)<\/em>\u00a0\u00e8 una pianta tropicale originaria dal Brasile, probabilmente della regione Amazzonica, che si \u00e8 diffusa in tutto il mondo a partire dal XVI secolo. Ha grande importanza economica e sociale, principalmente nel nord e nordest del Brasile.<br \/>\n&#8220;Caju&#8221; viene da &#8220;acaiu&#8221; (&#8220;noce che si produce&#8221;) dal dialetto indigena\u00a0&#8220;tupi&#8221;.<br \/>\nIl &#8220;caju&#8221; si divide in due parti: il frutto vero e proprio che \u00e8 la castagna e il pseudofrutto o peduncolo floreale che \u00e8 la parte che viene venduta come frutta e che pu\u00f2 essere mangiata fresca. \u00c8 ricco di vitamina C e B, ferro, calcio, fosforo e fibre.<br \/>\nCi sono circa 20 variet\u00e0 di &#8220;caju&#8221; che si differenziano per il sapore, la consistenza della polpa, il formato e il colore (giallo, rosso o viola-giallo). \u00c8 un frutto molto delicato, all&#8217;acquisto deve essere molto fresco, consistente e senza macchie sulla buccia, e deve essere mangiato molto maturo se no lega come il caco.<br \/>\nLa polpa viene industrializzata e utilizzata nella preparazione di succo, dolci, frutta sciroppata, gelati, liquori, sciroppi e aceto. La castagna, conosciuta internazionalmente come\u00a0<em>cashew nut<\/em>, viene industrializzata e servita come aperitivo, ma dalla castagna si pu\u00f2 ricavare anche farina e un ottimo olio commestibile. In natura la castagna \u00e8 avvolta da una buccia dura e piena di olio viscoso, che viene utilizzato come materia prima per l&#8217;industria.<\/div>\n<\/div>\n<div class=\"middle\">\n<div class=\"bigImage\">\n<div class=\"fonti\">Fonte: Portal S\u00e3o Francisco<br \/>\n<a><br \/>\n<\/a><\/div>\n<\/div>\n<div class=\"ricetteIngredienti\">\n<h4>Recipes<\/h4>\n<p><a href=\"https:\/\/saborbrasil.it\/en\/bobo-de-camarao-gamberi-in-salsa-di-manioca\/\" target=\"_blank\" rel=\"noopener\">Bob\u00f3 de camar\u00e3o\u00a0(Prawn in Creamy Cassava Sauce)<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto di Sydney Haddad. Il &#8220;cajueiro&#8221; (Anacardium occidentale L.)\u00a0\u00e8 una pianta tropicale originaria dal Brasile, probabilmente della regione Amazzonica, che si \u00e8 diffusa in tutto il mondo a partire dal XVI secolo. Ha grande importanza economica e sociale, principalmente nel nord e nordest del Brasile.&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-2025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingredienti-en"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":5,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":5662,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/posts\/2025\/revisions\/5662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media\/3847"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/en\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}