{"id":1780,"date":"2021-06-03T09:30:03","date_gmt":"2021-06-03T07:30:03","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=1780"},"modified":"2021-06-28T06:14:38","modified_gmt":"2021-06-28T04:14:38","slug":"la-riscoperta-della-tubaina","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/la-riscoperta-della-tubaina\/","title":{"rendered":"La riscoperta della &#8220;Tuba\u00edna&#8221;"},"content":{"rendered":"<p>Il termine &#8220;tuba\u00edna&#8221; si riferisce a una gamma di bibite a basso costo, di produzione e distribuzione regionale, con una forte presenza all&#8217;interno del Brasile, nelle zone in cui i grandi marchi del settore hanno tardato ad arrivare. Si tratta di una bevanda gasata analcolica dal sapore simile a quello della bibita &#8220;Guaran\u00e1&#8221;, a base di aromatizzanti tutti frutti, tra i quali si possono trovare guaran\u00e1 e zenzero. Le differenze di colore dipendono dal tempo di caramellizzazione degli zuccheri e ogni produttore ha la sua propria ricetta. La &#8220;tuba\u00edna&#8221; sembra pi\u00f9 dolce rispetto alle altre bibite, ma la quantit\u00e0 di zucchero utilizzato \u00e8 la stessa, fissata dalla legge al 10%. Deve essere sempre consumata ben fredda, e ha il vantaggio di armonizzare perfettamente con tutti i tipi di alimenti. L&#8217;abbinamento classico della &#8220;Tuba\u00edna&#8221; nei bar \u00e8 il panino con la mortadella.<br \/>\nCi sono molte controversie circa l&#8217;invenzione e la paternit\u00e0 di questo prodotto. Nel 1898 \u00e8 iniziata la produzione di &#8220;Cotuba\u00edna&#8221; nella citt\u00e0 di Piracicaba; la &#8220;Etuba\u00edna&#8221;, la bibita pi\u00f9 antica conosciuta con il marchio &#8220;Tuba\u00edna&#8221; sull&#8217;etichetta, della famiglia Orlando della citt\u00e0 di Piracicaba, viene prodotta dal 1913; nel 1932 la societ\u00e0 &#8220;Ferr\u00e1spari&#8221; della citt\u00e0 di Jundia\u00ed, produtrice di vini, liquori, vermouth, sciroppi e della caramella conosciuta come &#8220;Turba\u00edna&#8221;, ha smesso di produrre le caramelle e inizi\u00f2 a produrre una bibita con lo stesso nome e lo stesso sapore della caramella. La bibita &#8220;guaran\u00e1&#8221; inizi\u00f2 a essere fabbricata nel 1921 dalla &#8220;Ant\u00e1rctica&#8221; e nel 1927 dalla &#8220;Brahma&#8221;, i grandi marchi di birra e bibita in Brasile. Nel 1954 \u00e8 iniziata la produzione della &#8220;Ituba\u00edna&#8221;, la prima bibita prodotta artigianalmente dal Gruppo &#8220;Schincariol&#8221;, oggi di propriet\u00e0 di &#8220;Brasil Kirin&#8221;, della citt\u00e0 de Itu.<br \/>\nPer affrontare la concorrenza della produzione regionale le grandi multinazionali del settore hanno adottato una politica di annientamento delle &#8220;tuba\u00ednas&#8221;, avvalendosi di campagne pubblicitarie denigratorie, facendo pressione sui rivenditori, acquistando marchi e chiudendo fabbriche. Da alcuni anni per\u00f2 si \u00e8 innescato un processo di riscoperta del prodotto con il riconoscimento del loro valore culturale aggiunto &#8211; il consumo della &#8220;tuba\u00edna&#8221; \u00e8 associato alla memoria affettiva delle persone e ai pranzi domenicali in famiglia. Oggi la &#8220;tuba\u00edna&#8221; \u00e8 sinonimo di &#8220;bibita artigianale&#8221; e molte marche della piccola produzione hanno mantenuto la classica bottiglia di vetro a rendere da 600 ml, utilizzate anche per la birra. Simultaneamente, alcune dei grandi marchi hanno rilanciato il prodotto in nuova edizione.<\/p>\n<p>\u00c8 brasilianit\u00e0, latinit\u00e0, \u00e8 essere urbano e provinciale, popolare, pacchiano e alternativo. &#8220;Tuba\u00edna&#8221; \u00e8 semplicit\u00e0, ed \u00e8 un lusso. (Tubaina Bar, S\u00e3o Paulo)<\/p>\n<p><strong>Alcuni dei marchi pi\u00f9 noti di Tubaina:<\/strong><br \/>\n\u2022 Funada, Presidente Prudente, SP<br \/>\n\u2022 Ma\u00e7a Don, Ribeir\u00e3o Preto, SP<br \/>\n\u2022 Jaboti Cola, Jaboticabal, SP<br \/>\n\u2022 Cotuba, S\u00e3o Jos\u00e9 do Rio Preto, SP<br \/>\n\u2022 Guarapan, Belo Horizonte, MG<br \/>\n\u2022 Bar\u00e9, Manaus, AM, adquirido pela Ant\u00e1rctica<br \/>\n\u2022 Guaran\u00e1 Jesus, Maranh\u00e3o \u2022 Ituba\u00edna, Itu, SP<br \/>\n\u2022 Etuba\u00edna Orlando, Piracicaba, SP<br \/>\n\u2022 Tauba\u00edna, Taubat\u00e9, SP<br \/>\n\u2022 Cotuba, Piracicaba, SP<br \/>\n\u2022 Caja\u00edna, Cajamar, SP<br \/>\n\u2022 Tuba\u00edna Bacana, Boituva, SP<br \/>\n\u2022 Tuba\u00edna Funada, Presidente Prudente, SP<br \/>\n\u2022 Cristalina, Assis, MG<br \/>\n\u2022 Tatu\u00edna Rossi e Tuiuba\u00edna Vieira, Tatu\u00ed, SP<br \/>\n\u2022 Fruta\u00edna\u00a0Conven\u00e7\u00e3o, Itu, SP<br \/>\n\u2022 Tauba\u00edna Vedete, Sorocaba, SP<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2132\" src=\"https:\/\/saborbrasil.it\/wp-content\/uploads\/2021\/06\/1-Etubaina_Orlando_Piracicaba_blog-sol-caldeira-.jpg\" alt=\"-Sabor Brasil ricette di cucina Brasiliana\" width=\"315\" height=\"243\" data-kale-share-title=\"La riscoperta della \u201cTuba\u00edna\u201d\" data-kale-share-url=\"https:\/\/saborbrasil.it\/2021\/06\/03\/la-riscoperta-della-tubaina\/\" srcset=\"https:\/\/www.saborbrasil.it\/wp-content\/uploads\/2021\/06\/1-Etubaina_Orlando_Piracicaba_blog-sol-caldeira-.jpg 551w, https:\/\/www.saborbrasil.it\/wp-content\/uploads\/2021\/06\/1-Etubaina_Orlando_Piracicaba_blog-sol-caldeira--300x231.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/>\u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-537\" src=\"https:\/\/saborbrasil.it\/wp-content\/uploads\/2021\/06\/4-A-tubaina-Bacana_Boituva-SP_Coisa-Velha.jpg\" alt=\"-Sabor Brasil ricette di cucina Brasiliana\" width=\"325\" height=\"245\" data-kale-share-title=\"La riscoperta della \u201cTuba\u00edna\u201d\" data-kale-share-url=\"https:\/\/saborbrasil.it\/2021\/06\/03\/la-riscoperta-della-tubaina\/\"><\/p>\n<p><strong>Font<\/strong><strong>i:<\/strong><\/p>\n<p>\u2022 ABIR &#8211; Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de Refrigerantes e de Bebidas N\u00e3o Alco\u00f3licas<br \/>\n\u2022 Blog L\u00edngua e Cultura<br \/>\n\u2022 Confraria das Tuba\u00ednas<br \/>\n\u2022 Ferr\u00e1spari S\/A Ind. Com. de Bebidas<br \/>\n\u2022 Tuba\u00edna e afins<br \/>\n\u2022 Revista &#8220;Tuba\u00edna e afins&#8221;, n\u00b01, luglio 2011.<br \/>\n\u2022 Blog Manifesto Terreiroir<br \/>\n\u2022 Rivista \u00c9poca online<br \/>\n\u2022 Blog Sol Caldeira<br \/>\n\u2022 Blog do refri\u2026<br \/>\n\u2022 &#8220;Quando a Tuba\u00edna imperava nesta regi\u00e3o&#8221;, Correio de Itapetininga, 19.10.2012.<br \/>\n\u2022 Bar Tuba\u00edna<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il termine &#8220;tuba\u00edna&#8221; si riferisce a una gamma di bibite a basso costo, di produzione e distribuzione regionale, con una forte presenza all&#8217;interno del Brasile, nelle zone in cui i grandi marchi del settore hanno tardato ad arrivare. Si tratta di una bevanda gasata analcolica&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilidade"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=1780"}],"version-history":[{"count":7,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1780\/revisions"}],"predecessor-version":[{"id":6141,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1780\/revisions\/6141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/3892"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=1780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=1780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=1780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}