{"id":1929,"date":"2021-06-05T12:23:27","date_gmt":"2021-06-05T10:23:27","guid":{"rendered":"http:\/\/brasil.polardemo.it\/?p=1929"},"modified":"2021-06-21T18:17:26","modified_gmt":"2021-06-21T16:17:26","slug":"leite-condensado","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/leite-condensado\/","title":{"rendered":"Leite condensado"},"content":{"rendered":"<p>In Brasile esiste un vero culto dei dolci e della loro preparazione, tramandato dai portoghesi che amano i dolci ben dolci e che hanno portato la canna da zucchero dall\u2019Isola di Madeira. Non c\u2019\u00e8 credenza senza torta n\u2019\u00e8 pasto senza un <em>docinho de sobremesa<\/em>\u00a0(dessert) prima del <em>cafezinho<\/em>.<br \/>\nIl latte concentrato zuccherato \u00e8 arrivato in Brasile dalla Svizzera nel 1890 con una \u201c<em>mo\u00e7a<\/em>\u201d (signorina\/contadina) nella etichetta, ha conquistato le casalinghe e viene utilizzato nella preparazione e farcitura di torte, budini, pani, biscotti e dolcetti e, naturalmente, pu\u00f2 essere mangiato al naturale.<br \/>\nIn quasi tutte le ricette con il <em><strong>Leite Mo\u00e7a<\/strong><\/em>\u00a0si trova la dicitura: &#8220;1 lattina di <em><strong>Leite Mo\u00e7a<\/strong><\/em>, la stessa misura di&#8230;&#8221;, che vuol dire utilizzare la lattina (300 ml) svuotata del contenuto per misurare gli atri ingredienti.<br \/>\n<a><br \/>\nFonte: O doce Brasileiro, 3a Edi\u00e7\u00e3o, 1990, Nestl\u00e9 Industrial e Comercial Ltda.<br \/>\n<\/a><a><br \/>\n<\/a><a><br \/>\n<\/a><\/p>\n<h4>Receitas<\/h4>\n<p><a href=\"https:\/\/saborbrasil.it\/pt-br\/alfajor-de-amido-de-milho-biscotto-alfajor\/\" target=\"_blank\" rel=\"noopener\">&#8220;Alfajor&#8221; de amido de milho<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/batida-de-amendoim-arachidi\/\" target=\"_blank\" rel=\"noopener\">Batida de amendoim<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/batida-de-coco-cocco\/\" target=\"_blank\" rel=\"noopener\">Batida de coco<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/batida-de-morango-fragola\/\" target=\"_blank\" rel=\"noopener\">Batida de morango<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/beijinho-pasticcino-al-cocco\/\" target=\"_blank\" rel=\"noopener\">Beijinho<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/bolo-pega-marido-torta-acchiappa-marito\/\" target=\"_blank\" rel=\"noopener\">Bolo pega marido<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/bolo-prestigio-torta-di-cioccolato-con-cocco\/\" target=\"_blank\" rel=\"noopener\">Bolo Prest\u00edgio<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/brejeirices-biscotti-al-cocco\/\" target=\"_blank\" rel=\"noopener\">Brejeirices<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/brigadeirao-budino-al-cioccolato\/\" target=\"_blank\" rel=\"noopener\">Brigadeir\u00e3o<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/brigadeiro-pasticcino-al-cioccolato\/\" target=\"_blank\" rel=\"noopener\">Brigadeiro<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/brigadeiro-de-caipirinha-tartufini-alla-caipirinha\/\" target=\"_blank\" rel=\"noopener\">Brigadeiro de caipirinha<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/cafe-bombom-caffe-bombon\/\" target=\"_blank\" rel=\"noopener\">Caf\u00e9 bombom<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/cajuzinho-pasticcino-alle-arachidi\/\" target=\"_blank\" rel=\"noopener\">Cajuzinho<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/camafeu-de-nozes-pasticcini-alle-noci\/\" target=\"_blank\" rel=\"noopener\">Camafeu de nozes<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/cocada\/\" target=\"_blank\" rel=\"noopener\">Cocada<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/gelatina-mosaico\/\" target=\"_blank\" rel=\"noopener\">Gelatina mosaico<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/meia-de-seda\/\" target=\"_blank\" rel=\"noopener\">Meia de seda<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/mousse-de-limao-rapida\/\" target=\"_blank\" rel=\"noopener\">Mousse de lim\u00e3o r\u00e1pida<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/olho-de-sogra\/\" target=\"_blank\" rel=\"noopener\">Olho de sogra<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/picole-chicabon-caseiro\/\" target=\"_blank\" rel=\"noopener\">Picol\u00e9 &#8220;Chicabon&#8221; caseiro<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/pudim-de-leite-moca\/\" target=\"_blank\" rel=\"noopener\">Pudim de leite Mo\u00e7a<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/sequilhos-de-maizena-biscotti-di-amido-di-mais\/\" target=\"_blank\" rel=\"noopener\">Sequilhos de Maizena<\/a><br \/>\n<a href=\"https:\/\/saborbrasil.it\/pt-br\/torta-de-limao-crostata-al-limone\/\" target=\"_blank\" rel=\"noopener\">Torta de lim\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Brasile esiste un vero culto dei dolci e della loro preparazione, tramandato dai portoghesi che amano i dolci ben dolci e che hanno portato la canna da zucchero dall\u2019Isola di Madeira. Non c\u2019\u00e8 credenza senza torta n\u2019\u00e8 pasto senza un docinho de sobremesa\u00a0(dessert) prima&hellip;<\/p>\n","protected":false},"author":2,"featured_media":822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ingredientes"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=1929"}],"version-history":[{"count":3,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1929\/revisions"}],"predecessor-version":[{"id":5785,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/1929\/revisions\/5785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/822"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=1929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=1929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=1929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}