{"id":4276,"date":"2021-06-11T16:59:58","date_gmt":"2021-06-11T14:59:58","guid":{"rendered":"http:\/\/brasil.polardemo.it\/bolo-pega-marido-torta-acchiappa-marito\/"},"modified":"2021-06-11T17:03:54","modified_gmt":"2021-06-11T15:03:54","slug":"bolo-pega-marido-torta-acchiappa-marito","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/bolo-pega-marido-torta-acchiappa-marito\/","title":{"rendered":"Bolo pega marido"},"content":{"rendered":"\n<p><strong><strong><a href=\"https:\/\/youtu.be\/n9P3xcy132U\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO<\/a><\/strong><\/strong><\/p>\n\n\n\n<p><br>O \u201cbolo pega marido\u201d \u00e9 um bolo com consist\u00eancia de pudim, uma varia\u00e7\u00e3o da tradicional receita do pudim de leite condensado, enriquecida com o leite de coco e farinha. \u00c9 um bolo delicado com personalidade, muito f\u00e1cil e r\u00e1pido de fazer!<\/p>\n\n\n\n<p><br><strong>Ingredientes<\/strong><br>\u2022 1 lata de leite condensado (300 ml)<br>\u2022 3 ovos grandes<br>\u2022 150 g de a\u00e7\u00facar<br>\u2022 150 g de farinha de trigo (120 g se quiser bem macio)<br>\u2022 60 g de manteiga derretida<br>\u2022 200 ml de leite de coco<br>\u2022 300 ml de leite integral<br><strong>Para a cobertura (opcional):<\/strong><br>\u2022 200 ml de leite de coco<br>\u2022 40 g de a\u00e7\u00facar<br>\u2022 75 g de coco ralado desidratado<\/p>\n\n\n\n<p><strong>Preparo<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Bater os ingredientes no liquidificador ou com o liquidificador de imers\u00e3o at\u00e9 formar uma massa homog\u00eanea.<\/li><li>Untar e enfarinhar uma forma de pudim (com buraco no meio), eliminando o excesso de farinha.<\/li><li>Despejar a massa na forma.<\/li><li>Assar em forno preaquecido a 190\u00b0C por cerca de 40 minutos: quando espetar o bolo com um palito de dentes e este sair limpo est\u00e1 pronto.<\/li><li>Esperar 5 minutos e desenformar.<\/li><li>Preparar a cobertura (se quiser) levando ao fogo todos os ingredientes at\u00e9 ferver. Se o coco \u00e9 muito seco acrescentar um pouco de leite. Pode cobrir o bolo ainda quente ou colocar a cobertura na hora de servir sobre cada fatia.<\/li><\/ol>\n\n\n\n<p><em>Postado em : 07 Maggio 2020<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO O \u201cbolo pega marido\u201d \u00e9 um bolo com consist\u00eancia de pudim, uma varia\u00e7\u00e3o da tradicional receita do pudim de leite condensado, enriquecida com o leite de coco e farinha. \u00c9 um bolo delicado com personalidade, muito f\u00e1cil e r\u00e1pido&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52,47],"tags":[],"class_list":["post-4276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-doces","category-leite-condensado","category-receitas"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=4276"}],"version-history":[{"count":2,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4276\/revisions"}],"predecessor-version":[{"id":4283,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4276\/revisions\/4283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/4244"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=4276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=4276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=4276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}