{"id":4771,"date":"2021-06-14T11:01:41","date_gmt":"2021-06-14T09:01:41","guid":{"rendered":"http:\/\/brasil.polardemo.it\/bauru-do-ponto-chic-panino-bauru-del-ponto-chic\/"},"modified":"2021-06-14T11:06:32","modified_gmt":"2021-06-14T09:06:32","slug":"bauru-do-ponto-chic-panino-bauru-del-ponto-chic","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/bauru-do-ponto-chic-panino-bauru-del-ponto-chic\/","title":{"rendered":"Bauru do &#8220;Ponto Chic&#8221;"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/youtu.be\/mCJfAR43ObM\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO<\/a><\/strong><\/p>\n\n\n\n<p><br>A vers\u00e3o mais conhecida do sandu\u00edche &#8220;bauru&#8221;, que pode ser encontrada em todo o Brasil, \u00e9 preparada com presunto cozido, queijo prato e rodelas de tomate em p\u00e3o de forma tostado, e \u00e9 tamb\u00e9m muito utilizada no \u00e2mbito do &#8220;garde-manger&#8221;.<br>O bauru original por\u00e9m tem um toque mais sofisticado. Foi &#8220;inventado&#8221; numa noite de 1934 (?) por Casemiro Pinto Neto, que ditou &#8220;uma receita nutricionalmente equilibrada&#8221; ao chapeiro da lanchonete &#8220;Ponto Chic&#8221;, o &#8220;Sr. Carlos&#8221;. Casemiro, conhecido como Bauru, nome da sua cidade natal no interior de S\u00e3o Paulo, era um estudante de direito do largo S\u00e3o Francisco. No in\u00edcio os amigos pediam ao chapeiro o &#8220;sandu\u00edche do Bauru&#8221;, que acabou virando &#8220;bauru&#8221;.<br>O &#8220;Ponto Chic&#8221; tinha sido inaugurado em 1922 por Od\u00edlio Cecchini no Largo Paissandu, no centro da cidade de S\u00e3o Paulo, mas n\u00e3o tinha uma placa com o nome. Era um ano de grande fermenta\u00e7\u00e3o art\u00edstica e social promovida pela &#8220;Semana de Arte Moderna&#8221; e rapidamente o local passou a ser frequentado pela elite intelectual da cidade. Devido \u00e0 decora\u00e7\u00e3o acurada era afetuosamente conhecido como o &#8220;local chique&#8221;, que deu origem ao nome oficial. Em 1957 Casemiro tamb\u00e9m ensinou a receita a Jos\u00e9 Francisco J\u00fanior (Z\u00e9 do Skin\u00e3o), propriet\u00e1rio do &#8220;Bar do Skin\u00e3o&#8221; em Bauru. O &#8220;Ponto Chic&#8221; tornou-se muito famoso e acompanhou a evolu\u00e7\u00e3o da cidade, assim como o lento decl\u00ednio do centro a partir de 1970, encerrando as atividades em 1974. Em 1978 o &#8220;Ponto Chic&#8221; foi reaberto pelos atuais propriet\u00e1rios.<br>O &#8220;Projeto Certifica\u00e7\u00e3o do Tradicional Sandu\u00edche Bauru&#8221; do COMTUR (Conselho Municipal de Turismo de Bauru) \u00e9 um programa de certifica\u00e7\u00e3o e controle de qualidade que tutela a utiliza\u00e7\u00e3o da denomina\u00e7\u00e3o &#8220;Sandu\u00edche Bauru&#8221;. \u00c9 tamb\u00e9m em andamento no Iphan (Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional) um pedido para o registro do &#8220;bauru&#8221; como bem imaterial.<br>Fonte: <a href=\"https:\/\/www.pontochic.com.br\/ponto-chic-restaurante\" target=\"_blank\" rel=\"noopener\">Ponto Chic<\/a><\/p>\n\n\n\n<p><br><strong>Ingredientes<\/strong><br>\u2022 1 p\u00e3ozinho franc\u00eas de tamanho grande (80-100g)<br>\u2022 80 g de rosbife cortado em fatias bem finas, aproximadamente<br>\u2022 80 g de queijo* Prato fatiado, aproximadamente<br>\u2022 tomate<br>\u2022 picles<br>\u2022 sal<br>\u2022 or\u00e9gano<\/p>\n\n\n\n<p><strong>Preparo<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Cortar o tomate e o picles em rodelas finas. Temperar o tomate com sal e or\u00e9gano.<\/li><li>Esquentar um pouco de \u00e1gua em uma frigideira. Colocar o queijo na \u00e1gua e deixar derreter. Voc\u00ea tamb\u00e9m pode derreter o queijo no microondas.<\/li><li>Dividir o p\u00e3o em duas partes e retirar boa parte do miolo.<\/li><li>Colocar o rosbife cortado bem fino em uma das metades do p\u00e3o.<\/li><li>Cobrir com uma camada de tomate e uma camada de picles.<\/li><li>Na outra metade do p\u00e3o colocar o queijo derretido.<\/li><li>Fechar o sandu\u00edche. O calor do queijo vai aquecer levemente os outros ingredientes.<\/li><\/ol>\n\n\n\n<p>*Nota: a receita original indica queijos de tipo prato, gouda e estepe ou su\u00ed\u00e7o, em partes iguais.<\/p>\n\n\n\n<p><br><em>Postado em : 20 Febbraio 2014<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO A vers\u00e3o mais conhecida do sandu\u00edche &#8220;bauru&#8221;, que pode ser encontrada em todo o Brasil, \u00e9 preparada com presunto cozido, queijo prato e rodelas de tomate em p\u00e3o de forma tostado, e \u00e9 tamb\u00e9m muito utilizada no \u00e2mbito do&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,54],"tags":[],"class_list":["post-4771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receitas","category-salgados"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=4771"}],"version-history":[{"count":1,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4771\/revisions"}],"predecessor-version":[{"id":4776,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4771\/revisions\/4776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/4750"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=4771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=4771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=4771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}