{"id":4808,"date":"2021-06-14T11:22:42","date_gmt":"2021-06-14T09:22:42","guid":{"rendered":"http:\/\/brasil.polardemo.it\/batida-de-coco-cocco\/"},"modified":"2021-06-14T11:24:51","modified_gmt":"2021-06-14T09:24:51","slug":"batida-de-coco-cocco","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/batida-de-coco-cocco\/","title":{"rendered":"Batida de coco"},"content":{"rendered":"\n<p><br>A &#8220;batida de coco&#8221; \u00e9 um dos famosos aperitivos \u00e0 base de pinga e leite condensado. Pode ser preparado com anteced\u00eancia e se conserva por um longo per\u00edodo na geladeira.<br>Uma garrafa de batida \u00e9 uma \u00f3tima op\u00e7\u00e3o para presentear o anfitri\u00e3o de um jantar.<\/p>\n\n\n\n<p><br><strong>Ingredientes<\/strong><br>\u2022 200 ml de leite de coco<br>\u2022 1 lata de leite condensado<br>\u2022 300 ml de pinga<\/p>\n\n\n\n<p><strong>Preparo<\/strong><br>Bater todos os ingredientes, engarrafar e conservar na geladeira. Antes de servir agitar a garrafa.<br>Servir em copos baixos com gelo como aperitivo, e em c\u00e1lices pequenos como licor.<\/p>\n\n\n\n<p><br><em>Postado em : 11 Novembre 2011<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A &#8220;batida de coco&#8221; \u00e9 um dos famosos aperitivos \u00e0 base de pinga e leite condensado. Pode ser preparado com anteced\u00eancia e se conserva por um longo per\u00edodo na geladeira.Uma garrafa de batida \u00e9 uma \u00f3tima op\u00e7\u00e3o para presentear o anfitri\u00e3o de um jantar. Ingredientes\u2022&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,52,47,57],"tags":[],"class_list":["post-4808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-batidas-e-bebidas","category-leite-condensado","category-receitas","category-sem-gluten"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=4808"}],"version-history":[{"count":1,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4808\/revisions"}],"predecessor-version":[{"id":4810,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4808\/revisions\/4810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/3084"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=4808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=4808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=4808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}