{"id":4969,"date":"2021-06-14T18:00:04","date_gmt":"2021-06-14T16:00:04","guid":{"rendered":"http:\/\/brasil.polardemo.it\/arroz-de-carreteiro-riso-del-mulattiere\/"},"modified":"2021-06-14T18:02:43","modified_gmt":"2021-06-14T16:02:43","slug":"arroz-de-carreteiro-riso-del-mulattiere","status":"publish","type":"post","link":"https:\/\/www.saborbrasil.it\/pt-br\/arroz-de-carreteiro-riso-del-mulattiere\/","title":{"rendered":"Arroz de carreteiro"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/youtu.be\/HtwH9ZUC9iM\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO<\/a><\/strong><\/p>\n\n\n\n<p><br>O arroz de carreteiro \u00e9 um dos pratos emblem\u00e1ticos da cozinha tropeira e da cozinha ga\u00facha (juntamente com o churrasco). A receita original, nascida durante as longas viagens das tropas que percorriam e abasteciam o interior do Rio Grande do Sul, se tornou a refei\u00e7\u00e3o di\u00e1ria dos carreteiros. Era preparada somente com ingredientes locais (arroz e charque), muito substanciosos e n\u00e3o perec\u00edveis, que resistiam ao transporte nos carros de boi (carretas). O gado foi introduzido no Rio Grande do Sul no in\u00edcio do s\u00e9c. XVII, mas a produ\u00e7\u00e3o do charque come\u00e7ou somente no fim do s\u00e9c. XVIII, depois da grande seca no Nordeste que dizimou os rebanhos da regi\u00e3o. O prato tornou-se popular em todo o pa\u00eds e pode ser encontrado em diversas vers\u00f5es com ingredientes como, por exemplo, piment\u00e3o, tomate, ovos cozidos ou mesmo restos de churrasco ao inv\u00e9s de charque. No Nordeste e no Estado do Tocantins existe um prato muito similar conhecido como Arroz Maria Isabel, que \u00e9 preparado com carne seca ou de sol ao inv\u00e9s de charque, e servido com feij\u00e3o cozido e farofa de banana da terra.<\/p>\n\n\n\n<p><br><strong>Ingredientes<\/strong><br>\u2022 250 g de arroz agulhinha<br>\u2022 350 g de charque<br>\u2022 1 cebola m\u00e9dia<br>\u2022 2 dentes de alho<br>\u2022 pimenta malagueta, a gosto<br>\u2022 75 g de banha ou manteiga<br>\u2022 400 ml de \u00e1gua fervendo, aproximadamente<br>\u2022 sal, se precisar<\/p>\n\n\n\n<p><strong>Preparo<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Cortar o charque em peda\u00e7os pequenos, retirar os nervos e a gordura e deixar de molho na v\u00e9spera, trocando a \u00e1gua pelo menos 3 ou 4 vezes.<\/li><li>No dia seguinte jogar fora a \u00e1gua e cozinhar com pouca \u00e1gua em fogo baixo, at\u00e9 ficar bem macio. Escorrer, deixar esfriar e, se preferir, desfiar a carne.<\/li><li>Lavar bem o arroz para eliminar todo o amido e escorrer.<\/li><li>Picar a cebola, e o alho.<\/li><li>Colocar a banha ou a manteiga em uma panela grande e refogar o charque por alguns minutos.<\/li><li>Acrescentar a cebola picada e, depois que amolecer, juntar o alho picado e a pimenta e deixar refogar por mais alguns minutos. Agora seria o momento de acrescentar, se quiser, 1 tomate e 1 piment\u00e3o pequeno em cubinhos.<\/li><li>Juntar o arroz lavado e escorrido e deixar tostar por 2 minutos, sem parar de mexer. Acrescentar quase toda a \u00e1gua fervendo e misturar. Depois que levantar fervura abaixar o fogo, tampar e deixar cozinhar per cerca de 8 minutos. Acrescentar sal se necess\u00e1rio. Quando a \u00e1gua estiver totalmente absorvida controlar se o arroz est\u00e1 cozido. Se necess\u00e1rio acrescentar mais um pouco de \u00e1gua fervendo e deixar cozinhar por mais 1 ou 2 minutos.<\/li><li>Decorar com salsinha e cebolinha, a gosto.<\/li><li>Servir com feij\u00e3o mexido (prato t\u00edpico riograndense de feij\u00e3o engrossado com farinha de mandioca) ou com feij\u00e3o cozido.<\/li><\/ol>\n\n\n\n<p>Rendimento: 6 por\u00e7\u00f5es<\/p>\n\n\n\n<p><br><em>Postado em : 18 Novembre 2015<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLIQUE AQUI PRA ASSISTIR AO V\u00cdDEO O arroz de carreteiro \u00e9 um dos pratos emblem\u00e1ticos da cozinha tropeira e da cozinha ga\u00facha (juntamente com o churrasco). A receita original, nascida durante as longas viagens das tropas que percorriam e abasteciam o interior do Rio Grande&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,54,57],"tags":[],"class_list":["post-4969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receitas","category-salgados","category-sem-gluten"],"_links":{"self":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/comments?post=4969"}],"version-history":[{"count":2,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4969\/revisions"}],"predecessor-version":[{"id":4974,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/posts\/4969\/revisions\/4974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media\/4908"}],"wp:attachment":[{"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/media?parent=4969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/categories?post=4969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saborbrasil.it\/pt-br\/wp-json\/wp\/v2\/tags?post=4969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}